{"id":27,"date":"2017-12-10T21:03:50","date_gmt":"2017-12-10T21:03:50","guid":{"rendered":"http:\/\/www.spoiled1.nl\/index.php\/my-account\/"},"modified":"2017-12-10T21:03:50","modified_gmt":"2017-12-10T21:03:50","slug":"my-account","status":"publish","type":"page","link":"https:\/\/www.spoiled1.nl\/index.php\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.spoiled1.nl\/index.php\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}